{"id":5395,"date":"2026-03-18T14:10:05","date_gmt":"2026-03-18T17:10:05","guid":{"rendered":"https:\/\/www.erzinger.com.br\/?p=5395"},"modified":"2026-03-18T14:15:59","modified_gmt":"2026-03-18T17:15:59","slug":"alianza-erzinger-y-andes-technology-11","status":"publish","type":"post","link":"https:\/\/www.erzinger.com.br\/es\/alianza-erzinger-y-andes-technology-11\/","title":{"rendered":"Alianza Erzinger y Andes Technology"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5395\" class=\"elementor elementor-5395 elementor-5393\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27e2ad8 e-flex e-con-boxed e-con e-parent\" data-id=\"27e2ad8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4048147 elementor-widget elementor-widget-text-editor\" data-id=\"4048147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La misi\u00f3n de Erzinger es construir soluciones de excelencia en equipos de pretratamiento y pintura con nuestros clientes, y a trav\u00e9s de nuestra asociaci\u00f3n con <a href=\"https:\/\/www.andestechnology.com\/\">Andes Technology<\/a>, ampliaremos este objetivo a a\u00fan m\u00e1s pa\u00edses.<\/p><p>Andes es una empresa peruana que ofrece soluciones tecnol\u00f3gicas completas para mejorar la eficiencia y la productividad de los procesos industriales, as\u00ed como automatizaci\u00f3n inteligente para la industria y la educaci\u00f3n. En su asociaci\u00f3n con Erzinger, se encargar\u00e1 de atender a nuestros clientes en Per\u00fa, Chile, Bolivia y Ecuador. Los equipos seguir\u00e1n siendo producidos en Brasil, con la calidad Erzinger que ustedes ya conocen, pero ahora contaremos con el apoyo de Andes para instalaciones m\u00e1s \u00e1giles y eficientes en m\u00e1s pa\u00edses de Am\u00e9rica Latina.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4359 aligncenter\" src=\"https:\/\/erzinger.com.br\/wp-content\/uploads\/2024\/03\/whatsapp-image-2024-03-05-at-14.27.06-scaled.jpeg\" alt=\"\" width=\"691\" height=\"388\"><\/p><p>Otra gran ventaja ser\u00e1 la presencia de asistencia t\u00e9cnica capacitada en estos pa\u00edses. Andes cuenta con un gran equipo de servicio t\u00e9cnico que estar\u00e1 totalmente preparado para ayudar con el mantenimiento de sus equipos Erzinger y la capacitaci\u00f3n de los operadores.<\/p><p>Andes ha estado form\u00e1ndose con Erzinger, aprendiendo sobre las \u00faltimas tecnolog\u00edas de recubrimiento en polvo, recubrimiento l\u00edquido y e-coat. En esa ocasi\u00f3n, visitaron nuestro Centro Tecnol\u00f3gico con una l\u00ednea completa de m\u00e1quinas de recubrimiento en polvo, donde vieron simulaciones de los trabajos de pintura de algunos clientes y comprendieron c\u00f3mo se lleva a cabo cada proceso.<\/p><p>\u00abCreemos que el trabajo en equipo es fundamental para alcanzar nuestros objetivos, nos centramos en agilizar las soluciones y ofrecer resultados. Buscamos con entusiasmo nuevas formas de hacer las cosas, desafiando los paradigmas existentes y nuestros m\u00e9todos de trabajo para ofrecer soluciones tecnol\u00f3gicas a nuestros clientes.\u00bb &#8211; Andes Tecnolog\u00eda<\/p><p><img decoding=\"async\" class=\"wp-image-4360 aligncenter\" src=\"https:\/\/erzinger.com.br\/wp-content\/uploads\/2024\/03\/whatsapp-image-2024-03-05-at-14.23.57-scaled.jpeg\" alt=\"\" width=\"684\" height=\"384\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La misi\u00f3n de Erzinger es construir soluciones de excelencia en equipos de pretratamiento y pintura con nuestros clientes, y a trav\u00e9s de nuestra asociaci\u00f3n con Andes Technology, ampliaremos este objetivo a a\u00fan m\u00e1s pa\u00edses. Andes es una empresa peruana que ofrece soluciones tecnol\u00f3gicas completas para mejorar la eficiencia y la productividad de los procesos industriales, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5419,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2],"tags":[],"class_list":["post-5395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nao-categorizado","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura\" \/>\n<meta property=\"og:description\" content=\"La misi\u00f3n de Erzinger es construir soluciones de excelencia en equipos de pretratamiento y pintura con nuestros clientes, y a trav\u00e9s de nuestra asociaci\u00f3n con Andes Technology, ampliaremos este objetivo a a\u00fan m\u00e1s pa\u00edses. Andes es una empresa peruana que ofrece soluciones tecnol\u00f3gicas completas para mejorar la eficiencia y la productividad de los procesos industriales, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\" \/>\n<meta property=\"og:site_name\" content=\"Erzinger - Tecnologias em Equipamentos de Pintura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ERZINGER-Solues-em-Equipamentos-de-Pintura-133390766737750\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T17:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T17:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Natan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\"},\"author\":{\"name\":\"Natan\",\"@id\":\"https:\/\/www.erzinger.com.br\/#\/schema\/person\/30df68d9d6971ea56c3e3aa2468a7b29\"},\"headline\":\"Alianza Erzinger y Andes Technology\",\"datePublished\":\"2026-03-18T17:10:05+00:00\",\"dateModified\":\"2026-03-18T17:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\"},\"wordCount\":299,\"publisher\":{\"@id\":\"https:\/\/www.erzinger.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png\",\"articleSection\":[\"N\u00e3o categorizado\",\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\",\"url\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\",\"name\":\"Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura\",\"isPartOf\":{\"@id\":\"https:\/\/www.erzinger.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png\",\"datePublished\":\"2026-03-18T17:10:05+00:00\",\"dateModified\":\"2026-03-18T17:15:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage\",\"url\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png\",\"contentUrl\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png\",\"width\":1600,\"height\":838,\"caption\":\"CAXIAS DO SUL: Inscri\u00e7\u00f5es abertas para a Academia de pintura e pr\u00e9-tratamento!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.erzinger.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alianza Erzinger y Andes Technology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.erzinger.com.br\/#website\",\"url\":\"https:\/\/www.erzinger.com.br\/\",\"name\":\"Erzinger - Tecnologias em Equipamentos de Pintura\",\"description\":\"Erzinger - Tecnologias em Equipamentos de Pintura\",\"publisher\":{\"@id\":\"https:\/\/www.erzinger.com.br\/#organization\"},\"alternateName\":\"Erzinger - Tecnologias em Equipamentos de Pintura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.erzinger.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.erzinger.com.br\/#organization\",\"name\":\"Erzinger - Tecnologias em Equipamentos de Pintura\",\"alternateName\":\"Erzinger - Tecnologias em Equipamentos de Pintura\",\"url\":\"https:\/\/www.erzinger.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.erzinger.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2024\/01\/logo-erzinger-294x180px.png\",\"contentUrl\":\"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2024\/01\/logo-erzinger-294x180px.png\",\"width\":294,\"height\":180,\"caption\":\"Erzinger - Tecnologias em Equipamentos de Pintura\"},\"image\":{\"@id\":\"https:\/\/www.erzinger.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ERZINGER-Solues-em-Equipamentos-de-Pintura-133390766737750\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.erzinger.com.br\/#\/schema\/person\/30df68d9d6971ea56c3e3aa2468a7b29\",\"name\":\"Natan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g\",\"caption\":\"Natan\"},\"sameAs\":[\"https:\/\/erzinger.com.br\/\"],\"url\":\"https:\/\/www.erzinger.com.br\/es\/author\/natan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/","og_locale":"es_ES","og_type":"article","og_title":"Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura","og_description":"La misi\u00f3n de Erzinger es construir soluciones de excelencia en equipos de pretratamiento y pintura con nuestros clientes, y a trav\u00e9s de nuestra asociaci\u00f3n con Andes Technology, ampliaremos este objetivo a a\u00fan m\u00e1s pa\u00edses. Andes es una empresa peruana que ofrece soluciones tecnol\u00f3gicas completas para mejorar la eficiencia y la productividad de los procesos industriales, [&hellip;]","og_url":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/","og_site_name":"Erzinger - Tecnologias em Equipamentos de Pintura","article_publisher":"https:\/\/www.facebook.com\/ERZINGER-Solues-em-Equipamentos-de-Pintura-133390766737750\/","article_published_time":"2026-03-18T17:10:05+00:00","article_modified_time":"2026-03-18T17:15:59+00:00","og_image":[{"width":1600,"height":838,"url":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png","type":"image\/png"}],"author":"Natan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Natan","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#article","isPartOf":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/"},"author":{"name":"Natan","@id":"https:\/\/www.erzinger.com.br\/#\/schema\/person\/30df68d9d6971ea56c3e3aa2468a7b29"},"headline":"Alianza Erzinger y Andes Technology","datePublished":"2026-03-18T17:10:05+00:00","dateModified":"2026-03-18T17:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/"},"wordCount":299,"publisher":{"@id":"https:\/\/www.erzinger.com.br\/#organization"},"image":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png","articleSection":["N\u00e3o categorizado","Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/","url":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/","name":"Alianza Erzinger y Andes Technology - Erzinger - Tecnologias em Equipamentos de Pintura","isPartOf":{"@id":"https:\/\/www.erzinger.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage"},"image":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png","datePublished":"2026-03-18T17:10:05+00:00","dateModified":"2026-03-18T17:15:59+00:00","breadcrumb":{"@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#primaryimage","url":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png","contentUrl":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2026\/03\/Academia-Caxias-Sympla.png","width":1600,"height":838,"caption":"CAXIAS DO SUL: Inscri\u00e7\u00f5es abertas para a Academia de pintura e pr\u00e9-tratamento!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erzinger.com.br\/academia-erzinger-treinamento-em-equipamentos-de-pintura-e-pre-tratamento-em-caxias-do-sul-rs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.erzinger.com.br\/"},{"@type":"ListItem","position":2,"name":"Alianza Erzinger y Andes Technology"}]},{"@type":"WebSite","@id":"https:\/\/www.erzinger.com.br\/#website","url":"https:\/\/www.erzinger.com.br\/","name":"Erzinger - Tecnologias em Equipamentos de Pintura","description":"Erzinger - Tecnologias em Equipamentos de Pintura","publisher":{"@id":"https:\/\/www.erzinger.com.br\/#organization"},"alternateName":"Erzinger - Tecnologias em Equipamentos de Pintura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erzinger.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.erzinger.com.br\/#organization","name":"Erzinger - Tecnologias em Equipamentos de Pintura","alternateName":"Erzinger - Tecnologias em Equipamentos de Pintura","url":"https:\/\/www.erzinger.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.erzinger.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2024\/01\/logo-erzinger-294x180px.png","contentUrl":"https:\/\/www.erzinger.com.br\/wp-content\/uploads\/2024\/01\/logo-erzinger-294x180px.png","width":294,"height":180,"caption":"Erzinger - Tecnologias em Equipamentos de Pintura"},"image":{"@id":"https:\/\/www.erzinger.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ERZINGER-Solues-em-Equipamentos-de-Pintura-133390766737750\/"]},{"@type":"Person","@id":"https:\/\/www.erzinger.com.br\/#\/schema\/person\/30df68d9d6971ea56c3e3aa2468a7b29","name":"Natan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d9b49ced017714f7b5ce8160642fac18dda73e360d6bff13736c0063a7b71f1?s=96&d=mm&r=g","caption":"Natan"},"sameAs":["https:\/\/erzinger.com.br\/"],"url":"https:\/\/www.erzinger.com.br\/es\/author\/natan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/posts\/5395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/comments?post=5395"}],"version-history":[{"count":4,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/posts\/5395\/revisions"}],"predecessor-version":[{"id":5424,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/posts\/5395\/revisions\/5424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/media\/5419"}],"wp:attachment":[{"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/media?parent=5395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/categories?post=5395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erzinger.com.br\/es\/wp-json\/wp\/v2\/tags?post=5395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}